{"id":259,"date":"2023-02-10T15:54:48","date_gmt":"2023-02-10T19:54:48","guid":{"rendered":"https:\/\/canadatelecoms.ca\/sample-page\/"},"modified":"2026-08-31T10:06:55","modified_gmt":"2026-08-31T14:06:55","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/canadatelecoms.ca\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<section id=\"hero-slider-block_87af1948761f4d50055db07126b41a85\" class=\"hero-slider_block pt-0 pb-0\">\n\t<div class=\"slider\">\n\t\t<div class=\"acf-innerblocks-container\">\n<section id=\"hero-slide-block_33c069a5b9d3ace75a929cb3fcc09aeb\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">L\u2019avenir de la connectivit\u00e9 au Canada d\u00e9pend de la p\u00e9rennit\u00e9 des investissements<\/h1>\n\n\n\n<p class=\"is-style-lg\">Lors d\u2019une r\u00e9cente conf\u00e9rence organis\u00e9e par l\u2019Association canadienne des t\u00e9l\u00e9communications et la GSMA, des leaders du secteur des t\u00e9l\u00e9communications ont discut\u00e9 du r\u00f4le croissant de la connectivit\u00e9 dans l\u2019\u00e9conomie, la s\u00e9curit\u00e9 et la comp\u00e9titivit\u00e9 du Canada, ainsi que de l\u2019importance de soutenir les investissements n\u00e9cessaires \u00e0 son avenir num\u00e9rique.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/lavenir-de-la-connectivite-au-canada-depend-de-la-perennite-des-investissements\/\">En savoir plus<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/06\/Carousel-260601.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_4e37425f7182c1d627624c12be2ddf17\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">Investissement en t\u00e9l\u00e9communications &#8211; un pilier essentiel de l\u2019\u00e9conomie canadienne<\/h1>\n\n\n\n<p class=\"is-style-lg\">Le secteur canadien des t\u00e9l\u00e9communications continue de cr\u00e9er de la valeur pour les consommateurs tout en servant de socle d\u2019assise pour l\u2019\u00e9conomie, la productivit\u00e9, la s\u00e9curit\u00e9 et la r\u00e9silience du pays. Toutefois, selon un rapport de PricewaterhouseCoopers (PwC), la d\u00e9gradation des conditions d\u2019investissement dans ce secteur pose un risque pour le maintien de ces apports.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/05\/Investissement-en-telecommunications-un-pilier-essentiel-de-leconomie-canadienne.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/05\/Carousel-260520-FR.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_d0b05866af621d0a121ba7751ef33558\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">Offrir plus pour moins<\/h1>\n\n\n\n<p class=\"is-style-lg\">Alors que le co\u00fbt des produits de premi\u00e8re n\u00e9cessit\u00e9 comme le logement, l&rsquo;alimentation et le transport augmente plus rapidement que les revenus, les m\u00e9nages canadiens subissent des pressions li\u00e9es au co\u00fbt de la vie. Le secteur canadien des t\u00e9l\u00e9communications suit la tendance inverse. Ce rapport de PwC examine comment le secteur des t\u00e9l\u00e9communications offre davantage pour moins cher.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/03\/Offrir-plus-pour-moins-Comment-les-telecommunications-contribuent-a-reduire-le-cout-de-la-vie-des-menages-canadiens.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/03\/Carousel-260316-FR.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_9eabc86679863221d3bb5340ba810ffe\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">Faits et donn\u00e9es \u00e0 propos du secteur canadien des t\u00e9l\u00e9communications<\/h1>\n\n\n\n<p class=\"is-style-lg\">Connaissez-vous vraiment la contribution du secteur des t\u00e9l\u00e9communications \u00e0 l\u2019\u00e9conomie du pays et les investissements qu\u2019il effectue pour am\u00e9liorer la couverture et la performance des r\u00e9seaux afin de maximiser la valeur qu\u2019ils offrent? D\u00e9couvrez ce que les statistiques disent \u00e0 propos des r\u00e9seaux et de leur r\u00f4le pour soutenir les communaut\u00e9s et garder les Canadiens connect\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/centre-de-connaissances\/donnees-sur-lindustrie\/\">En savoir plus<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/08\/Carousel-260831-2.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_06a7281cf1be5a91faeb60ff7ce23971\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">De grands projets? Pas sans les entreprises de t\u00e9l\u00e9com<\/h1>\n\n\n\n<p class=\"is-style-lg\">Le Canada vient d\u2019amorcer une \u00e8re de grands projets d\u2019int\u00e9r\u00eat national, un virage qui, comme il se doit, am\u00e8re tous les paliers de gouvernement \u00e0 lancer de vastes chantiers pour transformer notre \u00e9conomie et renforcer notre place sur l\u2019\u00e9chiquier mondial. Il ne faut toutefois pas penser que ces projets pourront \u00eatre r\u00e9alis\u00e9s sans des r\u00e9seaux de t\u00e9l\u00e9communications de calibre mondial.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/news\/de-grands-projets-pas-sans-telecommunications\/\">En savoir plus<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2025\/10\/Carousel-251029.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_d4e115226b71976a3f6e07ef3955baac\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">Reconna\u00eetre les tentatives de fraude et les pr\u00e9venir<\/h1>\n\n\n\n<p class=\"is-style-lg\">Comme les fraudeurs d\u00e9ploient des tactiques sans cesse plus raffin\u00e9es pour d\u00e9rober vos renseignements personnels et financiers, la vigilance doit devenir une seconde nature. Se prot\u00e9ger commence par une saine prudence et la m\u00e9fiance syst\u00e9matique envers les appels et les messages non sollicit\u00e9s. Vous pouvez heureusement compter sur un vaste dispositif de protection int\u00e9gr\u00e9 qui travaille en coulisse pour vous prot\u00e9ger contre la fraude.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/consumer_resource\/antifraude\/\">Lire la suite<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2026\/08\/Carousel-260831-1-FR.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_06911916c727540fb8db78747eaaccfb\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-sm\">Soyez pr\u00eats. Restez connect\u00e9s.<\/h1>\n\n\n\n<p class=\"is-style-lg\">Les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames tels que les ouragans, les incendies de for\u00eat et les temp\u00eates de neige et de verglas sont de plus en plus fr\u00e9quents \u2014 mettant en p\u00e9ril la vie des Canadiens, endommageant les biens et posant un risque pour les infrastructures essentielles, y compris les r\u00e9seaux de t\u00e9l\u00e9communication. L\u2019Association canadienne des t\u00e9l\u00e9communications a mis en ligne le site TelecomSoyezPr\u00eat.ca o\u00f9 vous trouverez des conseils et les mesures \u00e0 prendre pour pouvoir continuer \u00e0 utiliser les r\u00e9seaux de communications pendant des pannes de courant et d\u2019autres \u00e9v\u00e8nements pouvant paralyser ces services.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-purple\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/telecomsoyezpret.ca\" target=\"_blank\" rel=\"noreferrer noopener\">Voir le site<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2024\/11\/Carousel-241114.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"hero-slide-block_665878ac3cde78ef2dad4e44972a64c6\" class=\"hero-slide_block\">\n\t<div class=\"container \">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row \">\n\t\t\t<div class=\"col-12 col-lg-6  pe-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h1 class=\"wp-block-heading is-style-lg\">Connecter les Canadiens<\/h1>\n\n\n\n<p class=\"is-style-lg\">L\u2019Association canadienne des t\u00e9l\u00e9communications repr\u00e9sente les organisations qui investissent dans les r\u00e9seaux de t\u00e9l\u00e9communications de classe mondiale du Canada, les construisent, les entretiennent et les exploitent. En travaillant en concertation avec nos membres, le gouvernement, les organismes de r\u00e9glementation et d\u2019autres parties prenantes, nous poussons pour faire adopter des politiques qui assureront que le Canada demeure un leader mondial en mati\u00e8re de t\u00e9l\u00e9communications et que tous les Canadiens puissent profiter des services et des r\u00e9seaux de calibre mondial du Canada.<\/p>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 ps-xl-5   text-lg-end \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image \" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/02\/banner-home.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<\/div>\t<\/div>\n\t<div class=\"slider-controls\">\n\t\t<button class=\"play-toggle\" >pause<\/button>\n\t<\/div>\n<\/section>\n\n<script>\njQuery(document).ready(function($){\n\t$('#hero-slider-block_87af1948761f4d50055db07126b41a85 .slider > .acf-innerblocks-container').slick({\n\t\tdots: true,\n\t\tarrows: true,\n\t\tautoplay: true,\n\t\tinfinite: true,\t\t\t\t\t\n\t\tfade: false,\n\t\tpauseOnHover: false,\n\t\tadaptiveHeight: true,\n\t\tautoplaySpeed: 8000,\n\t\tappendArrows: $('#hero-slider-block_87af1948761f4d50055db07126b41a85 .slider-controls'),\n\t\tappendDots: $('#hero-slider-block_87af1948761f4d50055db07126b41a85 .slider-controls')\n\n\t});\n\t$('#hero-slider-block_87af1948761f4d50055db07126b41a85 .play-toggle').click( function() {\t\t\n\t\tif ($(this).hasClass('pause')){\n\t\t\t$('.slick-slider').slick('slickPlay')  ;\n\t\t\t$(this).removeClass('pause');\n\t\t} else {\n\t\t\t$('.slick-slider').slick('slickPause');\n\t\t\t\n\t\t\t$(this).addClass('pause');\n\t\t}  \n\t});\n});\n<\/script>\n\n<section id=\"columns-image-content-block_5922452b7bc0a32e01716dae380ae4d7\" class=\"columns-image-content_block\">\n\t<div class=\"container pt-8 pb-8\">\t\t\t\t\n\t\t<div class=\"row align-items-center flex-column-reverse flex-lg-row-reverse \">\n\t\t\t<div class=\"col-12 col-lg-6 load-hidden fadein_up ps-xl-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h2 class=\"wp-block-heading\">L\u2019avenir du Canada passe par la connectivit\u00e9<\/h2>\n\n\n\n<p>La connectivit\u00e9 est essentielle pour favoriser la croissance \u00e9conomique du Canada et am\u00e9liorer le bien-\u00eatre social des Canadiens. Elle permet aux entreprises d\u2019\u00eatre plus productives tout en r\u00e9duisant leur empreinte \u00e9cologique, elle aide les gouvernements \u00e0 fournir des services essentiels \u00e0 la population et garde les Canadiens en contact avec leurs amis et leurs proches, peu importe o\u00f9 ils vivent. L\u2019Association canadienne des t\u00e9l\u00e9communications se consacre \u00e0 b\u00e2tir un avenir meilleur pour les Canadiens gr\u00e2ce \u00e0 la connectivit\u00e9. Apprenez-en plus sur nos priorit\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-link\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/nos-priorites\/\">Nos priorit\u00e9s<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5 mb-5 mb-lg-0 pe-xl-5 text-lg-center \">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"content-image load-hidden fadein_up\" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/02\/img-home-intro.png\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"stat-block-block_d748ad4e58315ba999161df27ba3994b\" class=\"stat-block_block is-style-purple pt-0 pb-8\">\n\t<div class=\"inner-bg\">\n\t\t<div class=\"container py-6\">\t\t\t\t\n\t\t\t<div class=\"row align-items-center flex-column flex-lg-row \">\n\t\t\t\t<div class=\"col-12 col-lg-6  mb-6 mb-lg-0  fadein_up\">\n\t\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p class=\"is-style-sm has-light-gray-color has-text-color\"><br>T\u00e9l\u00e9communications au Canada<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019impact de l\u2019industrie<\/h2>\n\n\n\n<p class=\"has-light-gray-color has-text-color\">L\u2019industrie canadienne des t\u00e9l\u00e9communications joue un r\u00f4le cl\u00e9 dans la croissance \u00e9conomique et le d\u00e9veloppement social du Canada.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-link\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/centre-de-connaissances\/\">En savoir plus dans notre centre de connaissances<\/a><\/div>\n<\/div>\n\n<\/div>\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-12 col-lg-6 ps-xl-5\">\n\t\t\t\t\t<div class=\"stats d-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stat fadein_up my-2 my-lg-3\">\n\t\t\t\t\t\t\t\t<h4 class=\"h1 mb-2\">Plus de 86<\/h4>\n\t\t\t\t\t\t\t\t<p class=\"lg text-orange mb-1\">milliards de dollars<\/p>\n\t\t\t\t\t\t\t\t<p class=\"text-lightgray\">de contribution directe au PIB (2025)<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stat fadein_up my-2 my-lg-3\">\n\t\t\t\t\t\t\t\t<h4 class=\"h1 mb-2\">Plus de 611&nbsp;000<\/h4>\n\t\t\t\t\t\t\t\t<p class=\"lg text-orange mb-1\"><\/p>\n\t\t\t\t\t\t\t\t<p class=\"text-lightgray\">emplois soutenus (2025)<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stat fadein_up my-2 my-lg-3\">\n\t\t\t\t\t\t\t\t<h4 class=\"h1 mb-2\">99,5&nbsp;%<\/h4>\n\t\t\t\t\t\t\t\t<p class=\"lg text-orange mb-1\"><\/p>\n\t\t\t\t\t\t\t\t<p class=\"text-lightgray\">des Canadiens ont une couverture mobile LTE (2024)<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stat fadein_up my-2 my-lg-3\">\n\t\t\t\t\t\t\t\t<h4 class=\"h1 mb-2\">N<sup>o<\/sup>&nbsp;1<\/h4>\n\t\t\t\t\t\t\t\t<p class=\"lg text-orange mb-1\">parmi les pays du G20<\/p>\n\t\t\t\t\t\t\t\t<p class=\"text-lightgray\">pour la qualit\u00e9 des r\u00e9seaux mobiles<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t\n<\/section>\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">L\u2019actualit\u00e9 des t\u00e9l\u00e9communications<\/h3>\n\n\n<section id=\"post-featured-and-list-block_2c231e115dae2e42e7a3003ae54ddbb8\" class=\"post-featured-and-list_block\">\n\t<div class=\"container pt-5 pb-5\">\t\t\t\t\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-6 col-xl-5 col-xxl-4\">\n\t\t\t\t\t\t<div class=\"post-featured-and-list_block__featured fadein_up\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/canadatelecoms.ca\/fr\/news\/association-senior-vice-president-eric-smith-opening-statement-to-indu-en-anglais-seulement\/\" class=\"\">\n\t\t\t\t\t\t\t\t<div class=\"thumbnail mb-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"sm mb-2\">juin 4, 2026<\/p>\n\t\t\t\t\t\t\t\t\t<h5 class=\"mb-4\">Canadian Telecommunications Association Senior Vice President Eric Smith: Opening Statement to the Standing Committee on Industry and Technology (INDU) (en anglais seulement)<\/h5>\n\t\t\t\t\t\t\t\t\t<p><p>Fraud is a serious issue. It causes financial harm, undermines confidence in digital services, and affects Canadians in every region of the country. The telecommunications industry takes this challenge seriously.<\/p>\n<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<hr class=\"fadein_up d-block d-lg-none mt-4 mb-3 pb-3\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-12 col-lg-6 offset-xl-1 offset-xxl-2\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"listitem fadein_up\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/canadatelecoms.ca\/fr\/news\/association-senior-vice-president-eric-smith-opening-statement-to-secu-en-anglais-seulement\/\" class=\"\">\n\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"sm mb-2\">mai 27, 2026<\/p>\n\t\t\t\t\t\t\t\t\t<h5 class=\"mb-4\">Canadian Telecommunications Association Senior Vice President Eric Smith: Opening Statement to the Standing Committee on Public Safety and National Security (SECU) (en anglais seulement)<\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<hr class=\"fadein_up mt-4 mb-3 pb-3\">\t\t\t\t\t\n\t\t\t\t\t<div class=\"listitem fadein_up\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/canadatelecoms.ca\/fr\/news\/selon-une-nouvelle-etude-la-degradation-des-conditions-dinvestissement-dans-les-telecommunications-menace-leconomie-la-productivite-et-la-resilience-des-infrastructures-numeriques-du-canada\/\" class=\"\">\n\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"sm mb-2\">mai 20, 2026<\/p>\n\t\t\t\t\t\t\t\t\t<h5 class=\"mb-4\">Selon une nouvelle \u00e9tude, la d\u00e9gradation des conditions d\u2019investissement dans les t\u00e9l\u00e9communications menace l\u2019\u00e9conomie, la productivit\u00e9 et la r\u00e9silience des infrastructures num\u00e9riques du Canada<\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<hr class=\"fadein_up mt-4 mb-3 pb-3\">\t\t\t\t\t\n\t\t\t\t\t<div class=\"listitem fadein_up\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/canadatelecoms.ca\/fr\/news\/lassociation-canadienne-des-telecommunications-et-la-gsma-reunissent-les-dirigeants-de-lindustrie-a-un-moment-constituant-un-point-de-rupture-pour-lavenir-de-la-connectivite-au-canada\/\" class=\"\">\n\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"sm mb-2\">mai 20, 2026<\/p>\n\t\t\t\t\t\t\t\t\t<h5 class=\"mb-4\">L\u2019Association canadienne des t\u00e9l\u00e9communications et la GSMA r\u00e9unissent les dirigeants de l\u2019industrie \u00e0 un moment constituant un \u00ab\u00a0point de rupture\u00a0\u00bb pour l\u2019avenir de la connectivit\u00e9 au Canada<\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-link\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/canadatelecoms.ca\/fr\/media-and-events\/\">M\u00e9dias et \u00e9v\u00e9nements<\/a><\/div>\n<\/div>\n\n\n<section id=\"programs-list-block_968f00657c48acda1a23cd172055bdf5\" class=\"programs-list_block pt-8 pb-0\">\n<div class=\"inner-bg\">\n\t<div class=\"container pb-6\">\t\t\t\t\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12 mb-2 mb-lg-5\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<div style=\"height:72px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center is-style-xs\">Programmes<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Des programmes qui ont un impact concret<\/h3>\n\n\n\n<p class=\"has-text-align-center is-style-lg\">Apprenez-en plus sur nos programmes qui soutiennent l\u2019accessibilit\u00e9, les dons de charit\u00e9, la protection des consommateurs et bien plus encore.<\/p>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3 mb-4\">\n\t\t\t\t\t<div class=\"card card--program fadein_up px-4 py-5\">\n\t\t\t\t\t\t<div class=\"card__image mb-4\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-DeviceCheckCanada-FR-300x70.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-DeviceCheckCanada-FR-300x70.png 300w, https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-DeviceCheckCanada-FR.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"card__body\">\n\t\t\t\t\t\t\t<div class=\"card__text\">\n\t\t\t\t\t\t\t\t<p>Outil de recherche permettant aux Canadiens de saisir un num\u00e9ro IMEI (identit\u00e9 internationale d\u2019\u00e9quipement mobile) pour d\u00e9terminer si un appareil cellulaire a \u00e9t\u00e9 d\u00e9clar\u00e9 perdu ou vol\u00e9, ce qui le rendrait inutilisable sur les r\u00e9seaux canadiens participants.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.devicecheck.ca\/fr\/accueil\/\" class=\"btn btn-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tV\u00e9rifier Appareil Canada\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3 mb-4\">\n\t\t\t\t\t<div class=\"card card--program fadein_up px-4 py-5\">\n\t\t\t\t\t\t<div class=\"card__image mb-4\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-Textw911-FR-300x70.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-Textw911-FR-300x70.png 300w, https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-Textw911-FR.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"card__body\">\n\t\t\t\t\t\t\t<div class=\"card__text\">\n\t\t\t\t\t\t\t\t<p>Service qui permet aux personnes sourdes, ayant une d\u00e9ficience auditive ou un trouble de la parole de communiquer avec les centres d\u2019appels d\u2019urgence par messages texte.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.textwith911.ca\/fr\/accueil\/\" class=\"btn btn-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTexto au 911\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3 mb-4\">\n\t\t\t\t\t<div class=\"card card--program fadein_up px-4 py-5\">\n\t\t\t\t\t\t<div class=\"card__image mb-4\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-txtca-300x70.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-txtca-300x70.png 300w, https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-txtca.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"card__body\">\n\t\t\t\t\t\t\t<div class=\"card__text\">\n\t\t\t\t\t\t\t\t<p>Carrefour d\u2019information sur l\u2019administration et l\u2019utilisation des num\u00e9ros abr\u00e9g\u00e9s communs pour faciliter les interactions entre les utilisateurs, les marques, les d\u00e9taillants, le gouvernement et d\u2019autres organisations par la messagerie texte.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.txt.ca\/fr\/\" class=\"btn btn-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTxt.ca\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-3 mb-4\">\n\t\t\t\t\t<div class=\"card card--program fadein_up px-4 py-5\">\n\t\t\t\t\t\t<div class=\"card__image mb-4\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-MobileGivingFoundation-FR-300x70.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-MobileGivingFoundation-FR-300x70.png 300w, https:\/\/canadatelecoms.ca\/wp-content\/uploads\/2023\/03\/logo-MobileGivingFoundation-FR.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"card__body\">\n\t\t\t\t\t\t\t<div class=\"card__text\">\n\t\t\t\t\t\t\t\t<p>Fondation dont la mission est de faciliter la collecte de dons de charit\u00e9 par messagerie texte et d\u2019aider les utilisateurs canadiens du sans-fil \u00e0 soutenir les causes qui leur tiennent le plus \u00e0 c\u0153ur.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.mobilegiving.ca\/fr\/\" class=\"btn btn-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFondation des dons sans fil\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<div class=\"text-center  \">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canadatelecoms.ca\/programs\/\" class=\"btn btn-link mt-5\">Programs<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>L\u2019actualit\u00e9 des t\u00e9l\u00e9communications<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-259","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/pages\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/comments?post=259"}],"version-history":[{"count":118,"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/pages\/259\/revisions"}],"predecessor-version":[{"id":4863,"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/pages\/259\/revisions\/4863"}],"wp:attachment":[{"href":"https:\/\/canadatelecoms.ca\/fr\/wp-json\/wp\/v2\/media?parent=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}